{"id":771,"date":"2017-12-13T16:38:10","date_gmt":"2017-12-13T19:38:10","guid":{"rendered":"http:\/\/www.policiacivil.ma.gov.br\/labld\/?p=771"},"modified":"2017-12-13T16:39:38","modified_gmt":"2017-12-13T19:39:38","slug":"mpma-inaugura-laboratorio-de-tecnologia-contra-a-lavagem-de-dinheiro","status":"publish","type":"post","link":"https:\/\/www.policiacivil.ma.gov.br\/labld\/mpma-inaugura-laboratorio-de-tecnologia-contra-a-lavagem-de-dinheiro\/","title":{"rendered":"MPMA INAUGURA LABORAT\u00d3RIO DE TECNOLOGIA CONTRA A LAVAGEM DE DINHEIRO"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>A investiga\u00e7\u00e3o sobre o destino do dinheiro de origem il\u00edcita, por meio da gest\u00e3o estrat\u00e9gica de dados e informa\u00e7\u00f5es, \u00e9 o alvo do trabalho do Laborat\u00f3rio de Tecnologia contra Lavagem de Dinheiro (LAB-LD), inaugurado pelo Minist\u00e9rio P\u00fablico do Maranh\u00e3o (MPMA) na manh\u00e3 desta ter\u00e7a-feira, 12.<\/p>\n<p>As instala\u00e7\u00f5es ficam na sede da Procuradoria Geral de Justi\u00e7a, em S\u00e3o Lu\u00eds, anexas ao Grupo de Atua\u00e7\u00e3o Especial de Combate \u00e0s Organiza\u00e7\u00f5es Criminosas (Gaeco).<\/p>\n<p><a href=\"http:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/12\/mp02.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-773\" src=\"http:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/12\/mp02.jpg\" alt=\"\" width=\"746\" height=\"497\" srcset=\"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/12\/mp02.jpg 746w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/12\/mp02-300x200.jpg 300w\" sizes=\"(max-width: 746px) 100vw, 746px\" \/><\/a><\/p>\n<p>A solenidade contou com a participa\u00e7\u00e3o de servidores, promotores e procuradores de justi\u00e7a, representantes da Pol\u00edcia Civil e do Poder Executivo estadual, al\u00e9m do representante do Minist\u00e9rio da Justi\u00e7a e coordenador da Rede Nacional de Laborat\u00f3rios de Tecnologia, Leonardo Terra.<\/p>\n<p><a href=\"http:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/12\/mp03.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-774\" src=\"http:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/12\/mp03.jpg\" alt=\"\" width=\"750\" height=\"560\" srcset=\"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/12\/mp03.jpg 750w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/12\/mp03-300x224.jpg 300w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/12\/mp03-86x64.jpg 86w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ao inaugurar o espa\u00e7o, o procurador-geral de justi\u00e7a, Luiz Gonzaga Martins Coelho, destacou o esfor\u00e7o do Minist\u00e9rio P\u00fablico do Maranh\u00e3o em combater a corrup\u00e7\u00e3o e promover o interc\u00e2mbio com outras institui\u00e7\u00f5es e unidades ministeriais do Brasil. \u201cEsse laborat\u00f3rio vai realizar um trabalho de rede que vai interligar os sistemas, ajudando a solucionar casos de corrup\u00e7\u00e3o de alta complexidade\u201d.<\/p>\n<p style=\"text-align: justify;\">Em rela\u00e7\u00e3o aos resultados esperados, o promotor de justi\u00e7a e coordenador do Gaeco, Marco Aur\u00e9lio Rodrigues, confirmou que a parceria com outros laborat\u00f3rios j\u00e1 iniciada no treinamento da equipe que vai trabalhar no LAB-LD permitir\u00e1 auxiliar promotores de justi\u00e7a de todo o Maranh\u00e3o em suas investiga\u00e7\u00f5es. &#8220;Trata-se, sem d\u00favida, de um grande avan\u00e7o para o Minist\u00e9rio P\u00fablico do Maranh\u00e3o&#8221;.<\/p>\n<p style=\"text-align: justify;\">O LAB-LD faz parte da Estrat\u00e9gia Nacional de Combate \u00e0 Corrup\u00e7\u00e3o e \u00e0 Lavagem de Dinheiro (Enccla), do Minist\u00e9rio da Justi\u00e7a. O primeiro laborat\u00f3rio do pa\u00eds foi instalado, em 2007, dentro da estrutura do Departamento de Recupera\u00e7\u00e3o de Ativos e Coopera\u00e7\u00e3o Jur\u00eddica Internacional (DRCI) da atual Secretaria Nacional de Justi\u00e7a e Cidadania (SNJ).<\/p>\n<p style=\"text-align: justify;\">O conjunto destes laborat\u00f3rios forma a Rede Nacional de Laborat\u00f3rios de Tecnologia (Rede-Lab), contando, ap\u00f3s a inaugura\u00e7\u00e3o da unidade do MPMA, com 41 em funcionamento no Brasil.<\/p>\n<p style=\"text-align: justify;\">De acordo com o coordenador da Rede Lab, Leonardo Terra, a expectativa \u00e9 ampliar a capacidade do Minist\u00e9rio P\u00fablico no combate aos crimes financeiros e ao crime organizado, por meio do interc\u00e2mbio de boas pr\u00e1ticas na utiliza\u00e7\u00e3o de softwares e ferramentas tecnol\u00f3gicas.<\/p>\n<p style=\"text-align: justify;\">\u201cO crime de lavagem de dinheiro conta com uma verdadeira engenharia para mascarar de onde vem o dinheiro e os bens dessas organiza\u00e7\u00f5es criminosas. As investiga\u00e7\u00f5es envolvem quebras de sigilos banc\u00e1rios e telef\u00f4nicos de pessoas f\u00edsicas e jur\u00eddicas, ou seja, s\u00e3o muitos dados a serem analisados e que exigem equipes preparadas para rastrear o caminho do dinheiro\u201d, explicou Terra.<\/p>\n<p style=\"text-align: justify;\">No mesmo sentido, a promotora de justi\u00e7a e coordenadora de Assuntos Estrat\u00e9gicos e Intelig\u00eancia, Jerusa Capistrano Bandeira, explicou que, devido \u00e0 complexidade dos crimes financeiros, h\u00e1 necessidade de instrumentalizar as investiga\u00e7\u00f5es de forma mais consistente e, por consequ\u00eancia, obter provas mais robustas contra os criminosos. \u201cO trabalho do LAB-LD vai permitir tra\u00e7ar um caminho mais claro do dinheiro desviado e provar os v\u00ednculos a fim de ampliar as chances de reaver o dinheiro desviado dos cofres p\u00fablicos ou obtido pela sonega\u00e7\u00e3o de impostos\u201d.<\/p>\n<p><strong>Texto:<\/strong>\u00a0CCOM-MPMA<\/p>\n<p><strong>Dispon\u00edvel em:<\/strong>\u00a0<a href=\"https:\/\/www.mpma.mp.br\/index.php\/lista-de-noticias-gerais\/11\/13876\">https:\/\/www.mpma.mp.br\/index.php\/lista-de-noticias-gerais\/11\/13876<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A investiga\u00e7\u00e3o sobre o destino do dinheiro de origem il\u00edcita, por meio da gest\u00e3o estrat\u00e9gica de dados e informa\u00e7\u00f5es, \u00e9 o alvo do trabalho do Laborat\u00f3rio de Tecnologia contra Lavagem de Dinheiro (LAB-LD), inaugurado pelo Minist\u00e9rio P\u00fablico do Maranh\u00e3o (MPMA) na manh\u00e3 desta ter\u00e7a-feira, 12. As instala\u00e7\u00f5es ficam na sede da Procuradoria Geral de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":772,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"yst_prominent_words":[596,608,117,610,257,594,347,600,60,606,85,101,62,588,598,586,602,592,604,590],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/12\/mp01.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8TCZr-cr","_links":{"self":[{"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/posts\/771"}],"collection":[{"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/comments?post=771"}],"version-history":[{"count":3,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/posts\/771\/revisions"}],"predecessor-version":[{"id":777,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/posts\/771\/revisions\/777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/media\/772"}],"wp:attachment":[{"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/media?parent=771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/categories?post=771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/tags?post=771"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/yst_prominent_words?post=771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}