{"id":710,"date":"2017-11-22T15:34:25","date_gmt":"2017-11-22T18:34:25","guid":{"rendered":"http:\/\/www.policiacivil.ma.gov.br\/labld\/?p=710"},"modified":"2017-11-22T17:12:18","modified_gmt":"2017-11-22T20:12:18","slug":"lab-ld-lanca-sisgestor-2-0","status":"publish","type":"post","link":"https:\/\/www.policiacivil.ma.gov.br\/labld\/lab-ld-lanca-sisgestor-2-0\/","title":{"rendered":"LAB-LD LAN\u00c7A SISGESTOR 2.0"},"content":{"rendered":"<p style=\"text-align: justify;\">O Laborat\u00f3rio de Tecnologia Contra a Lavagem de Dinheiro da Pol\u00edcia Civil do Maranh\u00e3o (LAB-LD\/PCMA) lan\u00e7ou neste m\u00eas de novembro (2017) a segunda vers\u00e3o do Sistema Gestor de Casos do LAB (SISGESTOR 2.0). O Sistema foi desenvolvido pelos pr\u00f3prios analistas de TI do LAB-LD\/PCMA, com utiliza\u00e7\u00e3o de tecnologias livres e levou um per\u00edodo de 8 meses para ser conclu\u00eddo com a implanta\u00e7\u00e3o de todas as suas funcionalidades.<\/p>\n<p style=\"text-align: justify;\">O SISGESTOR 2.0 consiste em um sistema interno de gest\u00e3o de casos. Com o sistema em funcionamento, o LAB-LD\/PCMA passa a gerir todas as solicita\u00e7\u00f5es de apoio t\u00e9cnico de forma inteiramente digital, desde a solicita\u00e7\u00e3o de abertura de Caso at\u00e9 a conclus\u00e3o e difus\u00e3o do correspondente relat\u00f3rio. Todas as informa\u00e7\u00f5es contidas no SISGESTOR 2.0 s\u00e3o gerenciadas em ambiente fechado e seguro.<\/p>\n<p style=\"text-align: justify;\">O SISGESTOR, na vers\u00e3o 2.0, permite, dentre outras fun\u00e7\u00f5es, a gest\u00e3o estat\u00edstica dos dados, com gera\u00e7\u00e3o de gr\u00e1ficos, tabelas e relat\u00f3rios autom\u00e1ticos com indicadores estat\u00edsticos intelig\u00edveis, tornando mais confi\u00e1vel, c\u00e9lere e eficiente o assessoramento da Coordena\u00e7\u00e3o do LAB-LD e da Administra\u00e7\u00e3o Superior da Pol\u00edcia Civil no processo de tomada de decis\u00e3o administrativa relacionada \u00e0 Unidade.<\/p>\n<p><a href=\"http:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis01.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-712\" src=\"http:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis01.png\" alt=\"\" width=\"1604\" height=\"665\" srcset=\"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis01.png 1604w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis01-300x124.png 300w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis01-768x318.png 768w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis01-1024x425.png 1024w\" sizes=\"(max-width: 1604px) 100vw, 1604px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis02.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-713\" src=\"http:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis02.png\" alt=\"\" width=\"1601\" height=\"521\" srcset=\"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis02.png 1601w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis02-300x98.png 300w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis02-768x250.png 768w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis02-1024x333.png 1024w\" sizes=\"(max-width: 1601px) 100vw, 1601px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">A necessidade de abertura de Caso de forma presencial dificultava o acionamento do LAB-LD\/PCMA, especialmente em rela\u00e7\u00e3o aos demandantes lotados no interior do Estado. Atualmente, com o SISGESTOR 2.0, os demandantes n\u00e3o precisam mais se deslocar at\u00e9 a sede do LAB-LD\/PCMA para abrir um Caso. A solicita\u00e7\u00e3o de abertura e o encaminhamento de documentos e dados s\u00e3o feitos de forma inteiramente digital e segura. O <a href=\"http:\/\/gestor.policiacivil.ma.gov.br\/form\/\"><u>formul\u00e1rio digital<\/u><\/a> \u00a0est\u00e1 dispon\u00edvel no site oficial do LAB-LD\/PCMA.<\/p>\n<p style=\"text-align: justify;\">Uma vez recebida a solicita\u00e7\u00e3o de abertura de Caso no LAB-LD\/PCMA, a tramita\u00e7\u00e3o do pedido segue um fluxo pr\u00f3prio, iniciando pelo despacho de aceita\u00e7\u00e3o do Caso pelo Coordenador, ap\u00f3s an\u00e1lise dos requisitos de admissibilidade, e encerrando com a confec\u00e7\u00e3o do relat\u00f3rio e difus\u00e3o ao demandante.<\/p>\n<p><a href=\"http:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis03.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-714\" src=\"http:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis03.png\" alt=\"\" width=\"1616\" height=\"792\" srcset=\"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis03.png 1616w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis03-300x147.png 300w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis03-768x376.png 768w, https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sis03-1024x502.png 1024w\" sizes=\"(max-width: 1616px) 100vw, 1616px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">A administra\u00e7\u00e3o e manuten\u00e7\u00e3o do SISGESTOR 2.0 \u00e9 feita pelos pr\u00f3prios analistas de TI do LAB-LD\/PCMA, sem que haja a necessidade de contrata\u00e7\u00e3o de m\u00e3o-de-obra terceirizada.<\/p>\n<p style=\"text-align: justify;\">A primeira vers\u00e3o do SISGESTOR foi apresentada em Bras\u00edlia, em mar\u00e7o deste ano (2017) por ocasi\u00e3o da 1\u00aa Oficina de Softwares de Gest\u00e3o da REDE-LAB <a href=\"http:\/\/www.policiacivil.ma.gov.br\/labld\/?p=228\">(<u>relembre aqui<\/u>)<\/a>, oportunidade em que foi recomendado \u00e0s demais Unidades que ainda n\u00e3o possuem um Sistema Gestor de Casos. Na ocasi\u00e3o, os analistas de TI do LAB-LD\/PCMA apresentaram o SISGESTOR ao lado de representantes do MP\/ES; MP\/BA e MP\/GO. As apresenta\u00e7\u00f5es se destacaram pelo car\u00e1ter inovador, na busca de solu\u00e7\u00f5es que melhor auxiliassem as institui\u00e7\u00f5es p\u00fablica no combate \u00e0 corrup\u00e7\u00e3o e \u00e0 lavagem de dinheiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Laborat\u00f3rio de Tecnologia Contra a Lavagem de Dinheiro da Pol\u00edcia Civil do Maranh\u00e3o (LAB-LD\/PCMA) lan\u00e7ou neste m\u00eas de novembro (2017) a segunda vers\u00e3o do Sistema Gestor de Casos do LAB (SISGESTOR 2.0). O Sistema foi desenvolvido pelos pr\u00f3prios analistas de TI do LAB-LD\/PCMA, com utiliza\u00e7\u00e3o de tecnologias livres e levou um per\u00edodo de 8 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"yst_prominent_words":[350,111,353,219,351,117,213,344,63,115,60,59,346,348,340,355,366,369,342,612],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-content\/uploads\/2017\/11\/sisgestor.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8TCZr-bs","_links":{"self":[{"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/posts\/710"}],"collection":[{"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/comments?post=710"}],"version-history":[{"count":4,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/posts\/710\/revisions"}],"predecessor-version":[{"id":719,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/posts\/710\/revisions\/719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/media\/711"}],"wp:attachment":[{"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/media?parent=710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/categories?post=710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/tags?post=710"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.policiacivil.ma.gov.br\/labld\/wp-json\/wp\/v2\/yst_prominent_words?post=710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}